{"id":65,"date":"2010-03-07T21:29:32","date_gmt":"2010-03-07T21:29:32","guid":{"rendered":"http:\/\/heinzjulen.com\/de\/press\/?p=65"},"modified":"2015-04-24T18:41:06","modified_gmt":"2015-04-24T17:41:06","slug":"lextension-zermatt-gastros-de-montagne","status":"publish","type":"post","link":"https:\/\/www.heinzjulen.com\/de\/press\/lextension-zermatt-gastros-de-montagne\/","title":{"rendered":"L&#8217;extension &#8211; Zermatt, Gastros de montagne"},"content":{"rendered":"<p>La station valaisanne est la destination pl\u00e9biscit\u00e9e des Romands. Mais finie l\u2019\u00e8re du Club alpin, c\u2019est devenu un village branch\u00e9 avec ses h\u00f4tels design et ses restaurants gastronomiques qui refusent du monde. Des bonnes tables pour des clients captifs. Mieux vaut r\u00e9server!<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abMalgr\u00e9 la distance et la diff\u00e9rence de langues, Zermatt reste la destination pl\u00e9biscit\u00e9e des Romands\u00bb, assure le magazine Bilan du mois de f\u00e9vrier sur la base d\u2019une analyse de l\u2019Institut de tourisme des HEC \u00e0 Lausanne. La station haut-valaisanne arrive nettement devant les autres leaders que sont Verbier, Crans-Montana, Saas-Fee et Villars-sur-Ollon (ndlr: Gstaad n\u2019a pas \u00e9t\u00e9 prise en consid\u00e9ration dans ce classement qui ne tient compte que des six cantons romands).<\/p>\n<p>Pour les cat\u00e9gories prestige, romantisme, sport pur-ski et culture, Zermatt arrive au 1er rang. Elle n\u2019obtient en revanche que le 2e rang derri\u00e8re Verbier, en ce qui concerne la gastronomie et le c\u00f4t\u00e9 festif. M\u00eame s\u2019il a pris sa retraite depuis belle lurette, il faut croire que le chef Roland Pierroz a laiss\u00e9 sa \u00abpatte\u00bb au pied du Mont-Fort! Est-ce dire que les gastronomes sont mal lotis \u00e0 Zermatt? C\u2019est loin d\u2019\u00eatre le cas. Les temps changent dans la station de Whymper, gr\u00e2ce notamment \u00e0 un pr\u00e9curseur du tourisme branch\u00e9, longtemps consid\u00e9r\u00e9 comme l\u2019\u00abenfant terrible\u00bb du village. L\u2019artiste zermattois Heinz Julen, 46 ans, a pos\u00e9 son empreinte dans tous les secteurs de la station: \u00abLe niveau des restaurants s\u2019est beaucoup am\u00e9lior\u00e9 en m\u00eame temps que les h\u00f4tels sont devenus moins conventionnels\u00bb, constate l\u2019homme-orchestre haut-valaisan. Il tient simultan\u00e9ment un bar, un cin\u00e9ma, une galerie d\u2019exposition et un magasin de meubles design regroup\u00e9s \u00e0 l\u2019enseigne du \u00abVernissage\u00bb, un restaurant gastro, le \u00abHeimberg\u00bb cot\u00e9 au GaultMillau, un bar branch\u00e9, le \u00abSnowboat\u00bb, et bient\u00f4t un h\u00f4tel design de 20 chambres qui s\u2019appellera \u00abBackstage\u00bb et que le jeune mari\u00e9 doit ouvrir \u00e0 la fin de l\u2019ann\u00e9e avec sa femme, Evelyne.<\/p>\n<p><strong>Des clients captifs<\/strong><br \/>\nHeinz Julen n\u2019est pas \u00e9tranger \u00e0 l\u2019\u00e9volution moderne de la station: \u00abIl y a vingt ans, les Zermattois me consid\u00e9raient un peu comme un illumin\u00e9, mais aujourd\u2019hui ils se frottent les mains\u00bb. C\u2019est le grand boom. Coup\u00e9e du r\u00e9seau routier, la station sans voitures vit certes un statut un peu particulier. C\u2019est un cas assez rare de client\u00e8le captive. Pas question de prendre son v\u00e9hicule pour aller d\u00eener ailleurs, ce n\u2019est tout simplement pas possible. Et pour aller o\u00f9? R\u00e9sultat: pratiquement tous les restaurants sont pleins durant les cinq mois de la saison d\u2019hiver. Si vous n\u2019avez pas r\u00e9serv\u00e9 \u00e0 17 h, vous pouvez oublier la bonne table, vous r\u00e9fugier au MacDo ou esp\u00e9rer au mieux un deuxi\u00e8me service vers 22 heures: \u00abLa grande \u00e9poque des r\u00f6sti et des cro\u00fbtes au fromage est derri\u00e8re nous. On peut le regretter, mais les touristes qui viennent \u00e0 Zermatt sont habitu\u00e9s \u00e0 bien boire et bien manger. Ils ne vont pas changer leurs habitudes. La qualit\u00e9 se paie, mais n\u2019allez pas croire que les restaurateurs gagnent beaucoup mieux leur vie. Leur chiffre d\u2019affaires augmente, mais leurs marges sont plus faibles.\u00bb<br \/>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-66\" src=\"https:\/\/heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_05.jpg\" alt=\"olivier_grivat_heinz_julen_05\" width=\"500\" height=\"234\" srcset=\"https:\/\/www.heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_05.jpg 500w, https:\/\/www.heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_05-300x140.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><br \/>\nM\u00eame sur les pistes de ski, les terrasses sont pleines au moindre rayon de soleil. D\u00e9sormais, le skieur a aussi int\u00e9r\u00eat \u00e0 r\u00e9server sa table \u00e0 midi, s\u2019il ne veut pas faire la queue \u00e0 l\u2019entr\u00e9e du restaurant d\u2019alpage: \u00abA l\u2019\u00e9poque de mon p\u00e8re &#8211; guide de montagne qui conduisait ses clients au sommet du Cervin mais servait aussi des r\u00f6sti-saucisses \u00e0 Findeln -, son restaurant \u00e9tait d\u00e9j\u00e0 une mine d\u2019or. Aujourd\u2019hui, l\u2019\u00abAlpenheim\u00bb est devenu \u00abChez Vrony\u00bb et il marche tout aussi fort mais avec une carte plus sophistiqu\u00e9e. Ma s\u0153ur Vrony a transform\u00e9 l\u2019\u00e9tablissement avec son mari Max Cotting, un financier zurichois qui dirige aussi le service durant le week-end\u00bb commente Heinz Julen. Il a fabriqu\u00e9 les chaises longues \u00e0 peau de vache install\u00e9es sur le bar-terrasse adjacent. Perch\u00e9 sur les hauteurs zermattoises dans un angle o\u00f9 le Cervin appara\u00eet sous son profil le plus photog\u00e9nique, ce restaurant d\u2019alpage est un vrai ph\u00e9nom\u00e8ne. On y c\u00f4toie des touristes parlant toutes les langues.<br \/>\n<a href=\"https:\/\/heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_04.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-67\" src=\"https:\/\/heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_04.jpg\" alt=\"olivier_grivat_heinz_julen_04\" width=\"500\" height=\"234\" srcset=\"https:\/\/www.heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_04.jpg 500w, https:\/\/www.heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_04-300x140.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><br \/>\nFigure embl\u00e9matique du sport helv\u00e9tique, le m\u00e9daill\u00e9 olympique Pirmin Zurbriggen est aussi un habitu\u00e9 de la terrasse. Il a du reste \u00e9pous\u00e9 l\u2019une des s\u0153urs de Vrony, avec laquelle il exploite plus bas, dans la station de Zermatt, un appart-h\u00f4tel romantique, d\u00e9cor\u00e9 l\u00e0 aussi par son beau-fr\u00e8re Heinz. D\u00e9cid\u00e9ment, une affaire de famille!<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-70\" src=\"https:\/\/heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_01.jpg\" alt=\"olivier_grivat_heinz_julen_01\" width=\"500\" height=\"234\" srcset=\"https:\/\/www.heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_01.jpg 500w, https:\/\/www.heinzjulen.com\/de\/press\/wp-content\/uploads\/2015\/04\/olivier_grivat_heinz_julen_01-300x140.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Autre personnalit\u00e9 (plus discr\u00e8te\u2026) de la station haut-valaisanne, le banquier priv\u00e9 genevois Ivan Pictet a rachet\u00e9 un vieil h\u00f4tel du quartier de Winkelmatten, qui \u00e9tait vou\u00e9 \u00e0 la d\u00e9molition. Pour \u00e9viter de voir l\u2019un des sites les plus photographi\u00e9s de Zermatt d\u00e9par\u00e9 par un volumineux b\u00e2timent, il a rachet\u00e9 l\u2019\u00e9tablissement et fait dresser \u00e0 la place un \u00e9l\u00e9gant restaurant, le \u00abSonnmatten\u00bb, devenu l\u2019une des bonnes tables de la station sous la houlette de son g\u00e9rant, Ren\u00e9 Foster. L\u00e0 aussi, les saveurs de la M\u00e9diterran\u00e9e ont remplac\u00e9 les r\u00f6sti-\u0153ufs-au-plat-raclettes. Elles tentent de faire oublier les odeurs de fromage et de pommes de terre r\u00f4ties.<\/p>\n<p>Les nostalgiques le d\u00e9ploreront, mais l\u2019\u00e9volution para\u00eet in\u00e9luctable.<br \/>\n<a href=\"http:\/\/www.hotellerieromande.ch\/\"><strong>Olivier Grivat<\/strong><\/a><\/p>\n<p><a href=\"http:\/\/www.lextension.com\/index.php?page=actu&amp;actionActu=det&amp;col=slp&amp;id_actu=14889\">http:\/\/www.lextension.com\/index.php?page=actu&amp;actionActu=det&amp;col=slp&amp;id_actu=14889<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La station valaisanne est la destination pl\u00e9biscit\u00e9e des Romands. Mais finie l\u2019\u00e8re du Club alpin, c\u2019est devenu un village branch\u00e9 avec ses h\u00f4tels design et ses restaurants gastronomiques qui refusent du monde. Des bonnes tables pour des clients captifs. Mieux vaut r\u00e9server! &nbsp; \u00abMalgr\u00e9 la distance et la diff\u00e9rence de langues, Zermatt reste la destination [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/posts\/65"}],"collection":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":2,"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":144,"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/posts\/65\/revisions\/144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/media\/68"}],"wp:attachment":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}