{"id":4,"count":21,"description":"","link":"https:\/\/www.heinzjulen.com\/de\/press\/category\/magazine-articles\/","name":"magazine articles","slug":"magazine-articles","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/categories\/4"}],"collection":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}