{"id":11,"count":1,"description":"","link":"https:\/\/www.heinzjulen.com\/de\/press\/category\/online-articles\/","name":"online articles","slug":"online-articles","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/categories\/11"}],"collection":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.heinzjulen.com\/de\/press\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}